{"id":4451,"date":"2025-12-11T20:40:20","date_gmt":"2025-12-11T20:40:20","guid":{"rendered":"https:\/\/fenixpestsolutions.com\/?page_id=4451"},"modified":"2026-05-06T10:33:44","modified_gmt":"2026-05-06T10:33:44","slug":"cafards","status":"publish","type":"page","link":"https:\/\/fenixpestsolutions.com\/en\/fr\/services\/cafards\/","title":{"rendered":"Cafards"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4451\" class=\"elementor elementor-4451\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-64557f8f elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"64557f8f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1d49ceba e-con-full e-flex e-con e-child\" data-id=\"1d49ceba\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2d649491 elementor-widget elementor-widget-heading\" data-id=\"2d649491\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contr\u00f4le des cafards \u00e0 Montr\u00e9al et au Qu\u00e9bec<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5bb35c0e elementor-widget elementor-widget-text-editor\" data-id=\"5bb35c0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Fenix Pest Solutions est un sp\u00e9cialiste reconnu des services de lutte contre les cafards \u00e0 Montr\u00e9al et au Qu\u00e9bec. Notre \u00e9quipe exp\u00e9riment\u00e9e utilise des m\u00e9thodes efficaces et \u00e9cologiques pour \u00e9liminer les cafards dans les maisons comme dans les entreprises. Nous r\u00e9alisons des inspections d\u00e9taill\u00e9es, \u00e9laborons des plans de traitement personnalis\u00e9s et assurons une protection continue pour garantir un environnement sans cafards et et assurer votre tranquillit\u00e9 d\u2019esprit. Faites confiance \u00e0 Fenix Pest Solution pour un contr\u00f4le des cafards fiable et performant.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3a254e3f e-con-full e-flex e-con e-child\" data-id=\"3a254e3f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-44bc87b1 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"44bc87b1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7ce92aae e-con-full e-flex e-con e-child\" data-id=\"7ce92aae\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6b6b7806 elementor-widget elementor-widget-heading\" data-id=\"6b6b7806\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Services de contr\u00f4le des cafards \u00e0 Montr\u00e9al et au Qu\u00e9bec<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43cc64a1 elementor-widget elementor-widget-text-editor\" data-id=\"43cc64a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les cafards \u00e0 Phoenix sont des nuisibles bien connus qui peuvent envahir maisons et entreprises, entra\u00eenant d\u2019importants risques sanitaires et d\u2019hygi\u00e8ne. Dans le climat particulier de Montr\u00e9al et du Qu\u00e9bec, o\u00f9 certaines conditions favorisent leur d\u00e9veloppement, les cafards peuvent facilement s\u2019adapter et se d\u00e9velopper rapidement. Fenix Pest Solutions comprend les d\u00e9fis li\u00e9s aux infestations de cafards dans cette r\u00e9gion et propose des services complets de lutte antiparasitaire pour prot\u00e9ger votre propri\u00e9t\u00e9 et votre bien-\u00eatre.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-610d4737 elementor-align-left elementor-tablet-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"610d4737\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-float\" href=\"tel:514-531-6074\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Appelez-Nous : 514-531-6074<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-437b5d91 e-con-full e-flex e-con e-child\" data-id=\"437b5d91\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3f902524 e-con-full e-flex e-con e-child\" data-id=\"3f902524\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3ab4755a elementor-widget elementor-widget-shortcode\" data-id=\"3ab4755a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"wpforms-container \" id=\"wpforms-11\"><form id=\"wpforms-form-11\" class=\"wpforms-validate wpforms-form\" data-formid=\"11\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/4451\" data-token=\"80e4e34662a3eaf8fd12e0e6edc2d62a\" data-token-time=\"1778705525\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-11-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label\" for=\"wpforms-11-field_0\">Nom Complet <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-11-field_0\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][0][first]\" placeholder=\"Pr\u00e9nom\" required><label for=\"wpforms-11-field_0\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-11-field_0-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][0][last]\" placeholder=\"Nom\" required><label for=\"wpforms-11-field_0-last\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">Last<\/label><\/div><\/div><\/div><div id=\"wpforms-11-field_8-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"8\"><label class=\"wpforms-field-label\">Services<\/label><ul id=\"wpforms-11-field_8\"><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-11-field_8_2\" name=\"wpforms[fields][8][]\" value=\"\ud83e\udeb3Cafards\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-11-field_8_2\">\ud83e\udeb3Cafards<\/label><\/li><li class=\"choice-8 depth-1\"><input type=\"checkbox\" id=\"wpforms-11-field_8_8\" name=\"wpforms[fields][8][]\" value=\"\ud83d\udecf\ufe0fPunaises de lit\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-11-field_8_8\">\ud83d\udecf\ufe0fPunaises de lit<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"checkbox\" id=\"wpforms-11-field_8_7\" name=\"wpforms[fields][8][]\" value=\"\ud83d\udc00Rats \/ Souris\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-11-field_8_7\">\ud83d\udc00Rats \/ Souris<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-11-field_8_4\" name=\"wpforms[fields][8][]\" value=\"\ud83d\udc1cFourmis\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-11-field_8_4\">\ud83d\udc1cFourmis<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-11-field_8_5\" name=\"wpforms[fields][8][]\" value=\"\ud83d\udd77\ufe0fAraign\u00e9es\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-11-field_8_5\">\ud83d\udd77\ufe0fAraign\u00e9es<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-11-field_8_3\" name=\"wpforms[fields][8][]\" value=\"\ud83d\udc1dGu\u00eapes\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-11-field_8_3\">\ud83d\udc1dGu\u00eapes<\/label><\/li><li class=\"choice-9 depth-1\"><input type=\"checkbox\" id=\"wpforms-11-field_8_9\" name=\"wpforms[fields][8][]\" value=\"\ud83c\udf41Punaises de l\u2019\u00e9rable\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-11-field_8_9\">\ud83c\udf41Punaises de l\u2019\u00e9rable<\/label><\/li><li class=\"choice-10 depth-1\"><input type=\"checkbox\" id=\"wpforms-11-field_8_10\" name=\"wpforms[fields][8][]\" value=\"\ud83d\udc1ePuces\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-11-field_8_10\">\ud83d\udc1ePuces<\/label><\/li><\/ul><\/div><div id=\"wpforms-11-field_6-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-11-field_6\">Courriel<\/label><input type=\"email\" id=\"wpforms-11-field_6\" class=\"wpforms-field-large\" name=\"wpforms[fields][6]\" placeholder=\"abcd@hotmail.com\" spellcheck=\"false\" ><\/div><div id=\"wpforms-11-field_3-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-11-field_3\">Num\u00e9ro de t\u00e9l\u00e9phone <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"number\" id=\"wpforms-11-field_3\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][3]\" placeholder=\"514-123-4567\" step=\"any\" required><\/div><div id=\"wpforms-11-field_7-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"7\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-11-field_7\">Message<\/label><textarea id=\"wpforms-11-field_7\" class=\"wpforms-field-large\" name=\"wpforms[fields][7]\" placeholder=\"D\u00e9crivez bri\u00e8vement le probl\u00e8me (type de parasite, logement, urgence, etc.)\" ><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-field wpforms-field-hp\"><label for=\"wpforms-11-field-hp\" class=\"wpforms-field-label\">Phone<\/label><input type=\"text\" name=\"wpforms[hp]\" id=\"wpforms-11-field-hp\" class=\"wpforms-field-medium\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"11\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/fenixpestsolutions.com\/en\/wp-json\/wp\/v2\/pages\/4451\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-11\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Obtenir un rappel\" aria-live=\"assertive\" value=\"wpforms-submit\">Obtenir un rappel<\/button><\/div><\/form><\/div>  <!-- .wpforms-container --><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1ba22ba8 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"1ba22ba8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-67cd1670 e-con-full e-flex e-con e-child\" data-id=\"67cd1670\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-31efd53e e-con-full e-flex e-con e-child\" data-id=\"31efd53e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-73558c6e elementor-widget elementor-widget-image\" data-id=\"73558c6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"400\" height=\"500\" src=\"https:\/\/fenixpestsolutions.com\/wp-content\/uploads\/2026\/01\/geotagged-cleanning.jpg\" class=\"attachment-large size-large wp-image-5096\" alt=\"Fenix Pest Solutions\" srcset=\"https:\/\/fenixpestsolutions.com\/wp-content\/uploads\/2026\/01\/geotagged-cleanning.jpg 400w, https:\/\/fenixpestsolutions.com\/wp-content\/uploads\/2026\/01\/geotagged-cleanning-240x300.jpg 240w, https:\/\/fenixpestsolutions.com\/wp-content\/uploads\/2026\/01\/geotagged-cleanning-10x12.jpg 10w\" sizes=\"(max-width: 400px) 100vw, 400px\" title=\"Fenix Pest Solutions | Cafards\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-43b4e39a e-con-full e-flex e-con e-child\" data-id=\"43b4e39a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-52e76923 elementor-widget elementor-widget-heading\" data-id=\"52e76923\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le d\u00e9fi des cafards \u00e0 Montr\u00e9al et au Qu\u00e9bec<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-284e847c elementor-widget elementor-widget-text-editor\" data-id=\"284e847c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L\u2019environnement d\u00e9sertique de Phoenix peut ne pas sembler propice aux infestations de cafards, mais ces insectes r\u00e9sistants se sont adapt\u00e9s pour prosp\u00e9rer dans les conditions arides de la r\u00e9gion. Les cafards, en particulier les esp\u00e8ces germaniques et am\u00e9ricaines, sont connus pour leur capacit\u00e9 \u00e0 se cacher dans les fissures, contaminer les aliments et transmettre des maladies. Sans intervention ad\u00e9quate, une infestation de cafards peut rapidement devenir incontr\u00f4lable.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35ce4e58 elementor-widget elementor-widget-heading\" data-id=\"35ce4e58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">L\u2019expertise de Fenix Pest Solutions dans la lutte contre les cafards<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-410f685b elementor-widget elementor-widget-text-editor\" data-id=\"410f685b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Fenix Pest Solution apporte des ann\u00e9es d\u2019exp\u00e9rience et une compr\u00e9hension approfondie des d\u00e9fis uniques li\u00e9s aux infestations de cafards \u00e0 Montr\u00e9al et au Qu\u00e9bec. Notre \u00e9quipe de sp\u00e9cialistes form\u00e9s s\u2019engage \u00e0 fournir des services de lutte contre les cafards efficaces et respectueux de l\u2019environnement, vous aidant \u00e0 \u00e9liminer ces nuisibles et \u00e0 maintenir un environnement de vie ou de travail sain.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4a72e752 e-con-full e-flex e-con e-child\" data-id=\"4a72e752\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-72c27ab9 e-con-full e-flex e-con e-child\" data-id=\"72c27ab9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-533c03c9 elementor-widget elementor-widget-heading\" data-id=\"533c03c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Notre processus de traitement des cafards<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5224fee9 elementor-widget elementor-widget-text-editor\" data-id=\"5224fee9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li><p>Inspection compl\u00e8te : Notre processus de contr\u00f4le des cafards commence par une inspection approfondie de votre propri\u00e9t\u00e9. Nos sp\u00e9cialistes identifient les cachettes, les points d\u2019entr\u00e9e et la gravit\u00e9 de l\u2019infestation, ce qui nous permet d\u2019adapter notre approche \u00e0 vos besoins sp\u00e9cifiques.<\/p><\/li><li><p>Plans de traitement personnalis\u00e9s : \u00c0 la suite de l\u2019inspection, nos sp\u00e9cialistes \u00e9laborent un plan de traitement des cafards personnalis\u00e9, con\u00e7u pour r\u00e9pondre \u00e0 votre situation unique. Ce plan inclut des strat\u00e9gies pour \u00e9liminer les cafards, pr\u00e9venir les infestations futures et am\u00e9liorer les pratiques d\u2019assainissement.<\/p><\/li><li><p>M\u00e9thodes efficaces et \u00e9cologiques : Fenix Pest Solution s\u2019engage \u00e0 utiliser des m\u00e9thodes efficaces et respectueuses de l\u2019environnement pour le contr\u00f4le des cafards. Nous utilisons une combinaison d\u2019app\u00e2ts, de r\u00e9gulateurs de croissance d\u2019insectes et de traitements cibl\u00e9s pour \u00e9liminer les cafards tout en minimisant l\u2019impact environnemental et les risques pour la sant\u00e9.<\/p><\/li><li><p>Conseils en assainissement : Les infestations de cafards sont souvent aggrav\u00e9es par un mauvais assainissement. Dans le cadre de nos services, nous fournissons des recommandations pour am\u00e9liorer les pratiques d\u2019hygi\u00e8ne, r\u00e9duire les attractifs et pr\u00e9venir de futures infestations.<\/p><\/li><li><p>Suivi continu et pr\u00e9vention : Notre engagement envers votre tranquillit\u00e9 d\u2019esprit va au-del\u00e0 du traitement initial. Nous proposons des plans de suivi et de pr\u00e9vention continue pour maintenir votre propri\u00e9t\u00e9 sans cafards, incluant des inspections r\u00e9guli\u00e8res et des recommandations de contr\u00f4le \u00e0 long terme.<\/p><\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-67f13c9c elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"67f13c9c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e0e6a0a e-con-full e-flex e-con e-child\" data-id=\"e0e6a0a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-125fa38c elementor-widget elementor-widget-heading\" data-id=\"125fa38c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">POURQUOI NOUS CHOISIR<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6de90104 elementor-widget elementor-widget-heading\" data-id=\"6de90104\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Votre expert de confiance en gestion parasitaire<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66e59375 elementor-widget elementor-widget-text-editor\" data-id=\"66e59375\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vous pouvez compter sur notre technologie de pointe pour traiter les infestations efficacement et garantir des r\u00e9sultats durables, tout en pla\u00e7ant votre bien-\u00eatre au premier plan. En d\u2019autres termes, Fenix Pest Solutions assure votre protection sans jamais compromettre votre s\u00e9curit\u00e9. Gr\u00e2ce \u00e0 notre service de lutte antiparasitaire \u00e0 Montr\u00e9al et au Qu\u00e9bec, nous offrons des solutions r\u00e9sidentielles parmi les mieux not\u00e9es.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-42c50f2d e-con-full e-flex e-con e-child\" data-id=\"42c50f2d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-131d6b9e e-con-full e-flex e-con e-child\" data-id=\"131d6b9e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-719bd976 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"719bd976\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInDown&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b1eb9e2 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"b1eb9e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-user\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M313.6 304c-28.7 0-42.5 16-89.6 16-47.1 0-60.8-16-89.6-16C60.2 304 0 364.2 0 438.4V464c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48v-25.6c0-74.2-60.2-134.4-134.4-134.4zM400 464H48v-25.6c0-47.6 38.8-86.4 86.4-86.4 14.6 0 38.3 16 89.6 16 51.7 0 74.9-16 89.6-16 47.6 0 86.4 38.8 86.4 86.4V464zM224 288c79.5 0 144-64.5 144-144S303.5 0 224 0 80 64.5 80 144s64.5 144 144 144zm0-240c52.9 0 96 43.1 96 96s-43.1 96-96 96-96-43.1-96-96 43.1-96 96-96z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u00c9quipe d\u2019experts\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tNotre \u00e9quipe de sp\u00e9cialistes cumule de nombreuses ann\u00e9es d\u2019exp\u00e9rience et est pr\u00eate \u00e0 vous aider \u00e0 vivre dans un environnement sans nuisibles.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-344dad55 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"344dad55\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInDown&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-822d607 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"822d607\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-star\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M528.1 171.5L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6zM388.6 312.3l23.7 138.4L288 385.4l-124.3 65.3 23.7-138.4-100.6-98 139-20.2 62.2-126 62.2 126 139 20.2-100.6 98z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tService cinq \u00e9toiles\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tGr\u00e2ce \u00e0 notre \u00e9quipe de confiance, vous pouvez toujours compter sur un service rapide, courtois et professionnel.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6e9eee5f e-con-full e-flex e-con e-child\" data-id=\"6e9eee5f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-15fd2d31 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"15fd2d31\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInDown&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6b9aecde elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"6b9aecde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tools\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M501.1 395.7L384 278.6c-23.1-23.1-57.6-27.6-85.4-13.9L192 158.1V96L64 0 0 64l96 128h62.1l106.6 106.6c-13.6 27.8-9.2 62.3 13.9 85.4l117.1 117.1c14.6 14.6 38.2 14.6 52.7 0l52.7-52.7c14.5-14.6 14.5-38.2 0-52.7zM331.7 225c28.3 0 54.9 11 74.9 31l19.4 19.4c15.8-6.9 30.8-16.5 43.8-29.5 37.1-37.1 49.7-89.3 37.9-136.7-2.2-9-13.5-12.1-20.1-5.5l-74.4 74.4-67.9-11.3L334 98.9l74.4-74.4c6.6-6.6 3.4-17.9-5.7-20.2-47.4-11.7-99.6.9-136.6 37.9-28.5 28.5-41.9 66.1-41.2 103.6l82.1 82.1c8.1-1.9 16.5-2.9 24.7-2.9zm-103.9 82l-56.7-56.7L18.7 402.8c-25 25-25 65.5 0 90.5s65.5 25 90.5 0l123.6-123.6c-7.6-19.9-9.9-41.6-5-62.7zM64 472c-13.2 0-24-10.8-24-24 0-13.3 10.7-24 24-24s24 10.7 24 24c0 13.2-10.7 24-24 24z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSolution optimale\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tNotre syst\u00e8me de traitement exclusif Tri-Bloc offre une protection trois fois plus efficace que les m\u00e9thodes traditionnelles, tout en garantissant la s\u00e9curit\u00e9 de votre famille, de vos animaux et de vos plantes.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-29781aa6 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"29781aa6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInDown&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-20378a60 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"20378a60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"500\" viewBox=\"0 0 375 374.999991\" height=\"500\" preserveAspectRatio=\"xMidYMid meet\"><defs><clipPath id=\"f708c2d052\"><path d=\"M 170.90625 200.578125 L 203.90625 200.578125 L 203.90625 233.578125 L 170.90625 233.578125 Z M 170.90625 200.578125 \" clip-rule=\"nonzero\"><\/path><\/clipPath><clipPath id=\"15ef992382\"><path d=\"M 10 16.445312 L 367 16.445312 L 367 352.445312 L 10 352.445312 Z M 10 16.445312 \" clip-rule=\"nonzero\"><\/path><\/clipPath><\/defs><path fill=\"#ffffff\" d=\"M 196.382812 220.703125 L 196.546875 221.050781 C 196.632812 221.234375 196.773438 221.375 196.941406 221.464844 C 197.109375 221.558594 197.308594 221.597656 197.511719 221.566406 C 197.914062 221.5 198.21875 221.183594 198.277344 220.785156 L 198.324219 220.40625 C 197.917969 220.054688 197.503906 219.660156 197.152344 219.242188 C 196.941406 219.746094 196.667969 220.242188 196.382812 220.703125 Z M 196.382812 220.703125 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#ffffff\" d=\"M 194.6875 213.011719 C 194.875 212.984375 195.261719 213.421875 195.492188 214.226562 C 195.226562 214.523438 195.109375 214.941406 195.230469 215.351562 L 195.28125 215.535156 L 197.816406 215.144531 L 197.808594 214.953125 C 197.796875 214.523438 197.554688 214.160156 197.21875 213.964844 C 197.191406 213.125 197.429688 212.589844 197.617188 212.5625 C 197.804688 212.535156 197.933594 212.355469 197.90625 212.167969 C 197.878906 211.980469 197.699219 211.847656 197.511719 211.878906 C 196.972656 211.960938 196.519531 212.640625 196.519531 213.804688 C 196.492188 213.808594 196.460938 213.808594 196.4375 213.8125 L 196.195312 213.851562 C 196.164062 213.855469 196.140625 213.863281 196.113281 213.867188 C 195.761719 212.753906 195.125 212.246094 194.585938 212.332031 C 194.398438 212.359375 194.269531 212.539062 194.296875 212.726562 C 194.324219 212.910156 194.5 213.039062 194.6875 213.011719 Z M 194.6875 213.011719 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#ffffff\" d=\"M 198.398438 215.742188 C 198.28125 215.644531 198.128906 215.605469 197.980469 215.628906 L 196.871094 215.800781 L 197.285156 218.464844 C 197.300781 218.574219 197.34375 218.675781 197.410156 218.761719 C 198.023438 219.53125 198.878906 220.234375 199.460938 220.671875 C 199.71875 220.863281 200.085938 220.664062 200.058594 220.34375 C 199.984375 219.414062 199.785156 217.863281 199.226562 216.851562 C 198.9375 216.3125 198.664062 215.960938 198.398438 215.742188 Z M 198.398438 215.742188 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#ffffff\" d=\"M 196.789062 218.542969 L 196.375 215.878906 L 195.269531 216.046875 C 195.117188 216.074219 194.984375 216.152344 194.902344 216.28125 C 194.714844 216.574219 194.558594 216.996094 194.441406 217.59375 C 194.214844 218.722656 194.492188 220.265625 194.707031 221.171875 C 194.777344 221.488281 195.1875 221.566406 195.375 221.304688 C 195.800781 220.714844 196.402344 219.785156 196.757812 218.867188 C 196.796875 218.761719 196.804688 218.652344 196.789062 218.542969 Z M 196.789062 218.542969 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#ffffff\" d=\"M 189.152344 222.820312 L 188.601562 223.355469 L 187.699219 222.707031 C 187.5625 222.609375 187.371094 222.636719 187.269531 222.769531 L 186.257812 224.09375 C 186.199219 224.011719 186.132812 223.9375 186.058594 223.863281 C 185.992188 223.796875 185.914062 223.742188 185.832031 223.695312 L 186.191406 222.574219 C 186.226562 222.460938 186.199219 222.34375 186.113281 222.261719 L 185.21875 221.367188 L 185.511719 220.714844 C 185.582031 220.5625 185.511719 220.375 185.355469 220.308594 C 185.199219 220.238281 185.019531 220.308594 184.949219 220.460938 L 184.570312 221.304688 C 184.519531 221.421875 184.542969 221.5625 184.632812 221.652344 L 185.550781 222.566406 L 185.246094 223.515625 C 185.136719 223.5 185.03125 223.492188 184.929688 223.492188 C 185.070312 223.242188 185.085938 222.996094 184.847656 222.757812 C 184.660156 222.574219 184.328125 222.457031 184 222.425781 L 183.386719 221.265625 L 183.636719 220.96875 C 183.734375 220.855469 183.71875 220.691406 183.605469 220.597656 C 183.496094 220.503906 183.332031 220.515625 183.238281 220.628906 L 182.875 221.0625 C 182.804688 221.140625 182.792969 221.257812 182.839844 221.351562 L 183.421875 222.453125 C 183.316406 222.480469 183.230469 222.523438 183.171875 222.578125 C 183.117188 222.632812 183.074219 222.722656 183.046875 222.824219 L 181.949219 222.246094 C 181.851562 222.195312 181.738281 222.207031 181.65625 222.277344 L 181.222656 222.640625 C 181.113281 222.730469 181.097656 222.898438 181.191406 223.011719 C 181.289062 223.121094 181.453125 223.136719 181.5625 223.042969 L 181.859375 222.789062 L 183.019531 223.402344 C 183.054688 223.730469 183.171875 224.066406 183.355469 224.25 C 183.59375 224.488281 183.835938 224.476562 184.089844 224.335938 C 184.089844 224.4375 184.097656 224.542969 184.109375 224.648438 L 183.160156 224.953125 L 182.246094 224.039062 C 182.152344 223.945312 182.015625 223.921875 181.898438 223.976562 L 181.054688 224.351562 C 180.894531 224.421875 180.828125 224.605469 180.898438 224.761719 C 180.96875 224.914062 181.152344 224.984375 181.308594 224.914062 L 181.957031 224.621094 L 182.855469 225.519531 C 182.9375 225.597656 183.058594 225.632812 183.167969 225.597656 L 184.289062 225.234375 C 184.332031 225.316406 184.390625 225.394531 184.457031 225.464844 C 184.527344 225.535156 184.605469 225.601562 184.6875 225.664062 L 183.363281 226.675781 C 183.230469 226.777344 183.203125 226.964844 183.300781 227.101562 L 183.949219 228.007812 L 183.410156 228.554688 C 183.292969 228.675781 183.292969 228.871094 183.414062 228.992188 C 183.535156 229.109375 183.730469 229.109375 183.847656 228.988281 C 183.847656 228.988281 183.847656 228.988281 183.851562 228.984375 L 184.570312 228.25 C 184.675781 228.144531 184.691406 227.980469 184.601562 227.855469 L 183.976562 226.988281 L 185.308594 225.964844 C 185.425781 225.996094 185.542969 226.015625 185.65625 226.015625 C 185.5 226.3125 185.484375 226.625 185.734375 226.972656 L 185.378906 228.023438 C 185.339844 228.136719 185.367188 228.257812 185.453125 228.34375 L 186.308594 229.199219 L 185.984375 229.917969 C 185.914062 230.074219 185.984375 230.257812 186.144531 230.324219 C 186.261719 230.378906 186.398438 230.351562 186.484375 230.261719 C 186.511719 230.238281 186.535156 230.207031 186.546875 230.167969 L 186.953125 229.253906 C 187.007812 229.136719 186.980469 229.003906 186.890625 228.910156 L 186.019531 228.042969 L 186.21875 227.449219 C 186.929688 227.976562 188.003906 228.308594 188.453125 227.859375 C 188.898438 227.414062 188.5625 226.335938 188.042969 225.628906 L 188.632812 225.429688 L 189.503906 226.296875 C 189.59375 226.390625 189.730469 226.414062 189.847656 226.359375 L 190.761719 225.957031 C 190.796875 225.9375 190.828125 225.917969 190.855469 225.894531 C 190.941406 225.804688 190.972656 225.667969 190.917969 225.550781 C 190.847656 225.394531 190.667969 225.324219 190.511719 225.394531 L 189.789062 225.714844 L 188.941406 224.859375 C 188.859375 224.773438 188.734375 224.746094 188.625 224.785156 L 187.570312 225.140625 C 187.226562 224.894531 186.910156 224.910156 186.613281 225.070312 C 186.613281 224.953125 186.597656 224.839844 186.566406 224.71875 L 187.585938 223.386719 L 188.457031 224.011719 C 188.578125 224.101562 188.746094 224.085938 188.851562 223.980469 L 189.585938 223.261719 C 189.585938 223.261719 189.585938 223.261719 189.585938 223.257812 C 189.707031 223.140625 189.710938 222.945312 189.589844 222.824219 C 189.46875 222.703125 189.273438 222.699219 189.152344 222.820312 Z M 189.152344 222.820312 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#ffffff\" d=\"M 187.550781 209.988281 L 187.175781 210.101562 L 186.328125 209.496094 C 186.246094 209.433594 186.148438 209.421875 186.054688 209.457031 L 185.042969 209.832031 C 184.890625 209.886719 184.8125 210.058594 184.867188 210.207031 C 184.925781 210.359375 185.089844 210.4375 185.246094 210.386719 L 186.113281 210.066406 L 186.949219 210.667969 C 187.027344 210.722656 187.117188 210.738281 187.207031 210.714844 L 187.898438 210.503906 C 188.074219 210.734375 188.265625 210.960938 188.484375 211.1875 L 187.882812 211.785156 C 187.796875 211.875 187.769531 212.007812 187.828125 212.117188 L 188.246094 213.023438 L 187.933594 213.613281 C 187.855469 213.757812 187.90625 213.9375 188.054688 214.015625 C 188.167969 214.078125 188.3125 214.054688 188.402344 213.964844 C 188.425781 213.941406 188.4375 213.917969 188.453125 213.894531 L 188.835938 213.171875 C 188.882812 213.09375 188.882812 212.996094 188.84375 212.910156 L 188.449219 212.058594 L 188.917969 211.589844 C 189.257812 211.886719 189.613281 212.136719 189.957031 212.328125 L 189.761719 213.332031 C 189.746094 213.414062 189.765625 213.5 189.816406 213.566406 L 190.1875 214.046875 L 189.933594 214.691406 C 189.875 214.847656 189.949219 215.019531 190.101562 215.078125 C 190.210938 215.121094 190.339844 215.089844 190.417969 215.011719 C 190.445312 214.984375 190.46875 214.949219 190.484375 214.910156 L 190.800781 214.105469 C 190.839844 214.007812 190.824219 213.898438 190.761719 213.816406 L 190.371094 213.308594 L 190.511719 212.589844 C 191.171875 212.847656 191.773438 212.894531 192.1875 212.675781 L 188.136719 208.613281 C 187.898438 208.835938 187.542969 209.109375 187.164062 209.203125 C 187.261719 209.460938 187.390625 209.722656 187.550781 209.988281 Z M 187.550781 209.988281 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#ffffff\" d=\"M 193.546875 207.992188 L 192.957031 208.308594 L 192.050781 207.886719 C 191.9375 207.832031 191.800781 207.859375 191.71875 207.945312 L 191.121094 208.542969 C 190.902344 208.328125 190.675781 208.132812 190.441406 207.960938 L 190.648438 207.269531 C 190.675781 207.183594 190.660156 207.085938 190.605469 207.011719 L 190.003906 206.171875 L 190.320312 205.304688 C 190.378906 205.152344 190.296875 204.980469 190.148438 204.925781 C 189.992188 204.871094 189.820312 204.949219 189.765625 205.101562 L 189.390625 206.113281 C 189.355469 206.203125 189.375 206.308594 189.429688 206.386719 L 190.039062 207.234375 L 189.921875 207.609375 C 189.65625 207.449219 189.394531 207.316406 189.140625 207.21875 C 189.046875 207.601562 188.769531 207.953125 188.550781 208.195312 L 192.605469 212.246094 C 192.824219 211.832031 192.78125 211.226562 192.523438 210.570312 L 193.242188 210.429688 L 193.75 210.824219 C 193.832031 210.886719 193.941406 210.902344 194.039062 210.859375 L 194.839844 210.546875 C 194.878906 210.527344 194.914062 210.507812 194.941406 210.480469 C 195.023438 210.398438 195.054688 210.273438 195.007812 210.160156 C 194.949219 210.007812 194.777344 209.933594 194.625 209.996094 L 193.980469 210.25 L 193.5 209.878906 C 193.433594 209.828125 193.347656 209.804688 193.261719 209.824219 L 192.261719 210.019531 C 192.066406 209.671875 191.820312 209.320312 191.523438 208.976562 L 191.992188 208.507812 L 192.84375 208.90625 C 192.925781 208.941406 193.023438 208.941406 193.105469 208.898438 L 193.824219 208.511719 C 193.851562 208.5 193.875 208.484375 193.894531 208.464844 C 193.984375 208.375 194.011719 208.234375 193.949219 208.113281 C 193.871094 207.96875 193.6875 207.914062 193.546875 207.992188 Z M 193.546875 207.992188 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#ffffff\" d=\"M 188.441406 206.667969 C 188.257812 206.484375 187.867188 206.421875 187.488281 206.453125 C 187.253906 205.820312 187.203125 205.160156 187.335938 204.539062 C 187.367188 204.394531 187.273438 204.25 187.128906 204.21875 C 186.984375 204.1875 186.839844 204.277344 186.808594 204.425781 C 186.664062 205.105469 186.707031 205.820312 186.9375 206.507812 C 186.808594 206.488281 186.667969 206.527344 186.566406 206.625 C 186.464844 206.726562 186.425781 206.863281 186.445312 206.996094 C 185.757812 206.769531 185.046875 206.722656 184.363281 206.871094 C 184.222656 206.902344 184.128906 207.046875 184.160156 207.1875 C 184.191406 207.332031 184.332031 207.425781 184.476562 207.394531 C 185.101562 207.257812 185.757812 207.316406 186.390625 207.550781 C 186.355469 207.925781 186.421875 208.316406 186.609375 208.503906 C 186.953125 208.847656 187.425781 208.503906 187.933594 207.996094 C 188.4375 207.484375 188.785156 207.015625 188.441406 206.667969 Z M 188.441406 206.667969 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#ffffff\" d=\"M 183.484375 217.597656 C 182.996094 217.292969 182.515625 216.875 182.058594 216.476562 C 181.988281 216.410156 181.917969 216.351562 181.847656 216.289062 C 181.851562 216.285156 181.855469 216.277344 181.859375 216.277344 C 182.234375 215.789062 182.207031 215.140625 181.800781 214.828125 C 181.394531 214.519531 180.757812 214.65625 180.386719 215.148438 C 180.375 215.160156 180.367188 215.171875 180.363281 215.1875 C 179.859375 214.902344 179.3125 214.71875 178.703125 214.71875 C 176.394531 214.71875 175.503906 216.671875 175.421875 218.597656 L 175.363281 218.597656 C 174.835938 218.597656 174.40625 219.027344 174.40625 219.554688 C 174.40625 220.082031 174.835938 220.511719 175.363281 220.511719 L 178.375 220.511719 C 178.570312 220.511719 178.726562 220.671875 178.726562 220.878906 C 178.726562 221.074219 178.570312 221.234375 178.375 221.234375 L 177.136719 221.234375 C 176.96875 221.234375 176.832031 221.367188 176.832031 221.535156 C 176.832031 221.703125 176.96875 221.839844 177.136719 221.839844 L 178.375 221.839844 C 178.902344 221.839844 179.332031 221.410156 179.332031 220.871094 C 179.332031 220.34375 178.902344 219.914062 178.375 219.914062 L 175.363281 219.914062 C 175.167969 219.914062 175.007812 219.753906 175.007812 219.558594 C 175.007812 219.363281 175.167969 219.207031 175.363281 219.207031 L 178.597656 219.207031 C 178.5625 218.082031 177.910156 217.945312 177.832031 217.933594 C 177.667969 217.910156 177.550781 217.761719 177.578125 217.597656 C 177.597656 217.433594 177.75 217.316406 177.910156 217.335938 C 178.347656 217.390625 179.167969 217.851562 179.207031 219.210938 L 182.78125 219.210938 C 183.355469 219.210938 183.816406 218.9375 183.933594 218.527344 C 184.03125 218.171875 183.863281 217.832031 183.484375 217.597656 Z M 181.417969 217.773438 C 181.1875 217.773438 181.007812 217.59375 181.007812 217.367188 C 181.007812 217.136719 181.1875 216.957031 181.417969 216.957031 C 181.644531 216.957031 181.824219 217.136719 181.824219 217.367188 C 181.824219 217.59375 181.644531 217.773438 181.417969 217.773438 Z M 181.417969 217.773438 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><g clip-path=\"url(#f708c2d052)\"><path fill=\"#ffffff\" d=\"M 187.5 200.578125 C 178.347656 200.578125 170.90625 208.023438 170.90625 217.171875 C 170.90625 226.324219 178.347656 233.765625 187.5 233.765625 C 196.648438 233.765625 204.09375 226.324219 204.09375 217.171875 C 204.09375 208.023438 196.648438 200.578125 187.5 200.578125 Z M 172.976562 217.171875 C 172.976562 213.539062 174.324219 210.226562 176.539062 207.675781 L 197 228.136719 C 194.449219 230.347656 191.136719 231.699219 187.503906 231.699219 C 179.492188 231.695312 172.976562 225.179688 172.976562 217.171875 Z M 198.460938 226.671875 L 178 206.210938 C 180.550781 204 183.867188 202.648438 187.5 202.648438 C 195.503906 202.648438 202.019531 209.164062 202.019531 217.167969 C 202.019531 220.804688 200.671875 224.121094 198.460938 226.671875 Z M 198.460938 226.671875 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/g><path fill=\"#ffffff\" d=\"M 263.839844 104.101562 C 263.117188 93.863281 259.054688 83.875 251.683594 76.027344 L 246.617188 80.8125 C 253.878906 88.519531 257.441406 98.703125 257.050781 108.777344 L 263.839844 104.101562 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#ffffff\" d=\"M 98.152344 189.769531 C 99.960938 189.9375 101.769531 190.019531 103.578125 190.019531 C 109.335938 190.019531 114.957031 189.128906 120.1875 187.515625 C 118.101562 193.472656 116.792969 199.816406 116.375 206.382812 L 221.046875 133.789062 C 221.105469 132.925781 221.160156 132.09375 221.160156 131.203125 C 221.160156 119.070312 215.011719 108.359375 205.6875 102.015625 L 215.039062 90.441406 L 211.421875 87.519531 L 201.597656 99.675781 C 196.871094 97.3125 191.554688 95.949219 185.90625 95.949219 C 178.867188 95.949219 172.328125 98.035156 166.847656 101.597656 L 155.46875 87.519531 L 151.851562 90.441406 L 163.089844 104.378906 C 155.496094 110.835938 150.652344 120.460938 150.652344 131.203125 C 150.652344 135.929688 151.601562 140.4375 153.296875 144.527344 C 138.1875 146.671875 122.832031 139.660156 114.984375 126.414062 C 106.441406 111.976562 108.613281 93.222656 120.296875 80.8125 L 115.207031 76.027344 C 101.40625 90.691406 98.875 112.867188 108.972656 129.949219 C 117.15625 143.777344 132.289062 151.875 147.984375 151.875 C 148.121094 151.875 148.316406 151.875 148.484375 151.875 C 138.132812 158.46875 129.648438 167.707031 123.972656 178.667969 C 116.542969 182.089844 107.804688 183.675781 98.789062 182.816406 C 78.839844 180.949219 61.730469 167.734375 57.222656 150.734375 L 50.488281 152.515625 C 55.746094 172.296875 75.335938 187.628906 98.152344 189.769531 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#ffffff\" d=\"M 60.117188 226.304688 L 54.273438 230.085938 C 57.277344 234.734375 61.089844 238.628906 65.347656 241.773438 L 71.523438 237.515625 C 67.070312 234.621094 63.121094 230.921875 60.117188 226.304688 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#ffffff\" d=\"M 268.738281 189.769531 C 291.554688 187.628906 311.167969 172.296875 316.398438 152.515625 L 309.667969 150.734375 C 305.160156 167.734375 288.046875 180.949219 268.097656 182.816406 C 261.421875 183.453125 254.882812 182.730469 248.925781 180.921875 C 244.894531 172.351562 239.105469 164.757812 232.09375 158.523438 L 100.238281 250.007812 C 101.878906 249.703125 103.546875 249.398438 105.191406 248.894531 C 111.394531 247.003906 116.960938 243.804688 121.632812 239.628906 C 132.207031 268.175781 156.996094 292.746094 185.90625 292.746094 C 213.8125 292.746094 237.824219 269.820312 248.957031 242.578125 C 252.796875 245.304688 257.050781 247.476562 261.699219 248.894531 C 265.929688 250.175781 270.242188 250.816406 274.523438 250.816406 C 289.523438 250.816406 304.101562 243.21875 312.617188 230.085938 L 306.773438 226.304688 C 297.480469 240.578125 279.785156 247.113281 263.730469 242.21875 C 259.167969 240.855469 255.046875 238.601562 251.460938 235.734375 C 254.101562 227.445312 255.632812 218.929688 255.632812 210.609375 C 255.632812 203.015625 254.382812 195.753906 252.15625 188.878906 C 255.773438 189.601562 259.5 190.019531 263.3125 190.019531 C 265.121094 190.019531 266.929688 189.9375 268.738281 189.769531 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><g clip-path=\"url(#15ef992382)\"><path fill=\"#ffffff\" d=\"M 342.25 184.402344 C 342.25 271.960938 270.992188 343.191406 183.457031 343.191406 C 129.898438 343.191406 82.484375 316.507812 53.714844 275.800781 L 314.507812 94.863281 C 331.980469 120.378906 342.25 151.207031 342.25 184.402344 Z M 24.640625 184.402344 C 24.640625 96.839844 95.898438 25.582031 183.457031 25.582031 C 232.09375 25.582031 275.667969 47.589844 304.824219 82.148438 L 45.148438 262.277344 C 32.125 239.269531 24.640625 212.695312 24.640625 184.402344 Z M 366.84375 58.582031 L 357.746094 45.421875 L 312.558594 76.777344 C 281.703125 39.773438 235.265625 16.207031 183.457031 16.207031 C 90.695312 16.207031 15.265625 91.636719 15.265625 184.402344 C 15.265625 214.671875 23.332031 243.082031 37.410156 267.648438 L 10.699219 286.179688 L 19.828125 299.3125 L 46.007812 281.144531 C 76.476562 324.296875 126.699219 352.566406 183.457031 352.566406 C 276.195312 352.566406 351.625 277.136719 351.625 184.402344 C 351.625 149.203125 340.773438 116.539062 322.214844 89.523438 L 366.84375 58.582031 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tGarantie sans nuisibles\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tSi les nuisibles reviennent, nous revenons aussi. C\u2019est la preuve de notre engagement envers vous, notre client.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a05ccdf e-flex e-con-boxed e-con e-parent\" data-id=\"a05ccdf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-267cee7 e-con-full e-flex e-con e-child\" data-id=\"267cee7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-29f15d4 elementor-widget elementor-widget-heading\" data-id=\"29f15d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Extermination de Cafards \u00e0 Montr\u00e9al <\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f792fe elementor-widget elementor-widget-text-editor\" data-id=\"6f792fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Fenix Pest Solutions est un expert de confiance en extermination de cafards \u00e0 Montr\u00e9al et en contr\u00f4le professionnel des cafards \u00e0 travers Montr\u00e9al et le Qu\u00e9bec. Notre \u00e9quipe exp\u00e9riment\u00e9e utilise des m\u00e9thodes s\u00e9curitaires, efficaces et respectueuses de l\u2019environnement pour \u00e9liminer les infestations de cafards dans les maisons et les entreprises.<\/p><p>Nous commen\u00e7ons par une inspection approfondie afin de localiser les cachettes, les points d\u2019entr\u00e9e et l\u2019ampleur de l\u2019infestation. Sur la base de nos constats, nous \u00e9laborons un plan de traitement personnalis\u00e9, adapt\u00e9 aux besoins de votre propri\u00e9t\u00e9. Notre approche combine l\u2019\u00e9limination imm\u00e9diate avec des strat\u00e9gies pr\u00e9ventives continues pour assurer un environnement durablement exempt de cafards.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0fae2bb e-con-full e-flex e-con e-child\" data-id=\"0fae2bb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6cb260f e-flex e-con-boxed e-con e-parent\" data-id=\"6cb260f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-fc7e8a3 e-con-full e-flex e-con e-child\" data-id=\"fc7e8a3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7740d82 elementor-widget elementor-widget-heading\" data-id=\"7740d82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Extermination Efficace de Cafards \u00e0 Montr\u00e9al et au Qu\u00e9bec <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-05ca190 elementor-widget elementor-widget-text-editor\" data-id=\"05ca190\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les cafards sont des nuisibles persistants pouvant envahir les maisons et les entreprises, cr\u00e9ant des probl\u00e8mes de sant\u00e9 et d\u2019hygi\u00e8ne. \u00c0 Montr\u00e9al et au Qu\u00e9bec, l\u2019environnement local peut offrir des conditions id\u00e9ales pour leur prolif\u00e9ration, leur permettant de s\u2019adapter et de se multiplier rapidement.<\/p><p>Fenix Pest Solutions se sp\u00e9cialise dans le contr\u00f4le des cafards \u00e0 Montr\u00e9al et au Qu\u00e9bec, offrant des services complets pour \u00e9liminer les infestations et pr\u00e9venir leur retour. Notre \u00e9quipe exp\u00e9riment\u00e9e comprend le comportement des esp\u00e8ces locales de cafards et utilise des m\u00e9thodes efficaces et respectueuses de l\u2019environnement pour prot\u00e9ger votre propri\u00e9t\u00e9 et assurer votre tranquillit\u00e9 d\u2019esprit.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d835db5 elementor-align-left elementor-tablet-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"d835db5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-float\" href=\"tel:514-531-6074\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Appelez-Nous : 514-531-6074<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f7099c3 e-con-full e-flex e-con e-child\" data-id=\"f7099c3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6ae74b4 e-con-full e-flex e-con e-child\" data-id=\"6ae74b4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-47fba7a elementor-widget elementor-widget-shortcode\" data-id=\"47fba7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"wpforms-container \" id=\"wpforms-11\"><form id=\"wpforms-form-11\" class=\"wpforms-validate wpforms-form\" data-formid=\"11\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/4451\" data-token=\"80e4e34662a3eaf8fd12e0e6edc2d62a\" data-token-time=\"1778705525\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-11-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label\" for=\"wpforms-11-field_0\">Nom Complet <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-11-field_0\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][0][first]\" placeholder=\"Pr\u00e9nom\" required><label for=\"wpforms-11-field_0\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-11-field_0-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][0][last]\" placeholder=\"Nom\" required><label for=\"wpforms-11-field_0-last\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">Last<\/label><\/div><\/div><\/div><div id=\"wpforms-11-field_8-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"8\"><label class=\"wpforms-field-label\">Services<\/label><ul id=\"wpforms-11-field_8\"><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-11-field_8_2\" name=\"wpforms[fields][8][]\" value=\"\ud83e\udeb3Cafards\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-11-field_8_2\">\ud83e\udeb3Cafards<\/label><\/li><li class=\"choice-8 depth-1\"><input type=\"checkbox\" id=\"wpforms-11-field_8_8\" name=\"wpforms[fields][8][]\" value=\"\ud83d\udecf\ufe0fPunaises de lit\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-11-field_8_8\">\ud83d\udecf\ufe0fPunaises de lit<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"checkbox\" id=\"wpforms-11-field_8_7\" name=\"wpforms[fields][8][]\" value=\"\ud83d\udc00Rats \/ Souris\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-11-field_8_7\">\ud83d\udc00Rats \/ Souris<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-11-field_8_4\" name=\"wpforms[fields][8][]\" value=\"\ud83d\udc1cFourmis\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-11-field_8_4\">\ud83d\udc1cFourmis<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-11-field_8_5\" name=\"wpforms[fields][8][]\" value=\"\ud83d\udd77\ufe0fAraign\u00e9es\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-11-field_8_5\">\ud83d\udd77\ufe0fAraign\u00e9es<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-11-field_8_3\" name=\"wpforms[fields][8][]\" value=\"\ud83d\udc1dGu\u00eapes\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-11-field_8_3\">\ud83d\udc1dGu\u00eapes<\/label><\/li><li class=\"choice-9 depth-1\"><input type=\"checkbox\" id=\"wpforms-11-field_8_9\" name=\"wpforms[fields][8][]\" value=\"\ud83c\udf41Punaises de l\u2019\u00e9rable\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-11-field_8_9\">\ud83c\udf41Punaises de l\u2019\u00e9rable<\/label><\/li><li class=\"choice-10 depth-1\"><input type=\"checkbox\" id=\"wpforms-11-field_8_10\" name=\"wpforms[fields][8][]\" value=\"\ud83d\udc1ePuces\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-11-field_8_10\">\ud83d\udc1ePuces<\/label><\/li><\/ul><\/div><div id=\"wpforms-11-field_6-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-11-field_6\">Courriel<\/label><input type=\"email\" id=\"wpforms-11-field_6\" class=\"wpforms-field-large\" name=\"wpforms[fields][6]\" placeholder=\"abcd@hotmail.com\" spellcheck=\"false\" ><\/div><div id=\"wpforms-11-field_3-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-11-field_3\">Num\u00e9ro de t\u00e9l\u00e9phone <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"number\" id=\"wpforms-11-field_3\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][3]\" placeholder=\"514-123-4567\" step=\"any\" required><\/div><div id=\"wpforms-11-field_7-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"7\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-11-field_7\">Message<\/label><textarea id=\"wpforms-11-field_7\" class=\"wpforms-field-large\" name=\"wpforms[fields][7]\" placeholder=\"D\u00e9crivez bri\u00e8vement le probl\u00e8me (type de parasite, logement, urgence, etc.)\" ><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-field wpforms-field-hp\"><label for=\"wpforms-11-field-hp\" class=\"wpforms-field-label\">Phone<\/label><input type=\"text\" name=\"wpforms[hp]\" id=\"wpforms-11-field-hp\" class=\"wpforms-field-medium\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"11\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/fenixpestsolutions.com\/en\/wp-json\/wp\/v2\/pages\/4451\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-11\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Obtenir un rappel\" aria-live=\"assertive\" value=\"wpforms-submit\">Obtenir un rappel<\/button><\/div><\/form><\/div>  <!-- .wpforms-container --><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f64fee7 e-flex e-con-boxed e-con e-parent\" data-id=\"f64fee7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-76c5198 e-con-full e-flex e-con e-child\" data-id=\"76c5198\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-04ef96f e-con-full e-flex e-con e-child\" data-id=\"04ef96f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-846af01 elementor-widget elementor-widget-image\" data-id=\"846af01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"400\" height=\"500\" src=\"https:\/\/fenixpestsolutions.com\/wp-content\/uploads\/2026\/01\/geotagged-cleanning.jpg\" class=\"attachment-large size-large wp-image-5096\" alt=\"Fenix Pest Solutions\" srcset=\"https:\/\/fenixpestsolutions.com\/wp-content\/uploads\/2026\/01\/geotagged-cleanning.jpg 400w, https:\/\/fenixpestsolutions.com\/wp-content\/uploads\/2026\/01\/geotagged-cleanning-240x300.jpg 240w, https:\/\/fenixpestsolutions.com\/wp-content\/uploads\/2026\/01\/geotagged-cleanning-10x12.jpg 10w\" sizes=\"(max-width: 400px) 100vw, 400px\" title=\"Fenix Pest Solutions | Cafards\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-25b9a0b e-con-full e-flex e-con e-child\" data-id=\"25b9a0b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70352d8 elementor-widget elementor-widget-heading\" data-id=\"70352d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contr\u00f4le des Cafards \u00e0 Montr\u00e9al et au Qu\u00e9bec <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8ea20a elementor-widget elementor-widget-text-editor\" data-id=\"d8ea20a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLes cafards sont des nuisibles r\u00e9silients pouvant envahir les maisons et les entreprises \u00e0 Montr\u00e9al et au Qu\u00e9bec, pr\u00e9sentant des risques s\u00e9rieux pour l\u2019hygi\u00e8ne et la sant\u00e9. Ces insectes, incluant des esp\u00e8ces courantes comme les cafards allemands et am\u00e9ricains, peuvent se cacher dans les fissures, contaminer les aliments et propager des bact\u00e9ries. Sans intervention professionnelle, une infestation de cafards peut rapidement devenir un probl\u00e8me majeur. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa0f369 elementor-widget elementor-widget-heading\" data-id=\"aa0f369\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Gestion Professionnelle des Cafards \u00e0 Montr\u00e9al et au Qu\u00e9bec <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a18036 elementor-widget elementor-widget-text-editor\" data-id=\"9a18036\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tFenix Pest Solutions poss\u00e8de une vaste exp\u00e9rience dans le contr\u00f4le des cafards \u00e0 Montr\u00e9al et au Qu\u00e9bec. Nos sp\u00e9cialistes form\u00e9s comprennent le comportement des esp\u00e8ces locales de cafards et les d\u00e9fis qu\u2019elles repr\u00e9sentent. En utilisant des m\u00e9thodes efficaces et respectueuses de l\u2019environnement, nous fournissons des services complets de contr\u00f4le des cafards pour \u00e9liminer les infestations et aider \u00e0 maintenir un environnement s\u00fbr, sain et sans nuisibles dans votre maison ou votre entreprise. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-39dba2d e-con-full e-flex e-con e-child\" data-id=\"39dba2d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-17de170 e-con-full e-flex e-con e-child\" data-id=\"17de170\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ed1005e elementor-widget elementor-widget-heading\" data-id=\"ed1005e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Notre Processus d\u2019Extermination des Cafards <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-411182d elementor-widget elementor-widget-text-editor\" data-id=\"411182d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li><strong>Inspection Compl\u00e8te de la Propri\u00e9t\u00e9<\/strong><br \/>Nos services de contr\u00f4le des cafards commencent par une inspection approfondie de votre propri\u00e9t\u00e9. Chez Fenix Pest Solutions, nous identifions les cachettes, les points d\u2019entr\u00e9e et l\u2019ampleur de l\u2019infestation. Cette \u00e9valuation d\u00e9taill\u00e9e nous permet de concevoir un plan de traitement adapt\u00e9 \u00e0 vos besoins sp\u00e9cifiques.<br \/><br \/><\/li><li><strong>Plans de Traitement Personnalis\u00e9s<\/strong><br \/>Apr\u00e8s l\u2019inspection, nos sp\u00e9cialistes \u00e9laborent un plan de traitement des cafards personnalis\u00e9. Chaque plan vise \u00e0 \u00e9liminer les infestations existantes, \u00e0 pr\u00e9venir de futures invasions et \u00e0 recommander des pratiques d\u2019hygi\u00e8ne pour r\u00e9duire les sources d\u2019attraction.<br \/><br \/><\/li><li><strong>M\u00e9thodes S\u00e9curitaires et Efficaces<\/strong><br \/>Nous utilisons des m\u00e9thodes respectueuses de l\u2019environnement, \u00e0 la fois efficaces et s\u00e9curitaires pour votre famille, vos animaux et l\u2019environnement. Notre approche combine app\u00e2ts, r\u00e9gulateurs de croissance des insectes et traitements cibl\u00e9s afin d\u2019assurer une \u00e9limination compl\u00e8te des cafards.<br \/><br \/><\/li><li><strong>Conseils en Hygi\u00e8ne<\/strong><br \/>Les infestations de cafards sont souvent aggrav\u00e9es par une mauvaise hygi\u00e8ne et des sources de nourriture ou d\u2019eau accessibles. Dans le cadre de notre service, nous fournissons des conseils pratiques pour am\u00e9liorer la propret\u00e9 et minimiser les conditions attirant les nuisibles.<br \/><br \/><\/li><li><strong>Suivi et Pr\u00e9vention Continue<\/strong><br \/>Notre engagement ne s\u2019arr\u00eate pas apr\u00e8s le traitement initial. Fenix Pest Solutions offre un suivi continu, des inspections de contr\u00f4le et des strat\u00e9gies pr\u00e9ventives pour maintenir votre propri\u00e9t\u00e9 exempte de cafards, vous garantissant une protection durable et une tranquillit\u00e9 d\u2019esprit.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e43ba62 e-flex e-con-boxed e-con e-parent\" data-id=\"e43ba62\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a4f7d22 e-con-full e-flex e-con e-child\" data-id=\"a4f7d22\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-86a88e8 elementor-widget elementor-widget-heading\" data-id=\"86a88e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">POURQUOI NOUS CHOISIR<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f39d83e elementor-widget elementor-widget-heading\" data-id=\"f39d83e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vos Experts de Confiance en Gestion des Nuisibles <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6adc59c elementor-widget elementor-widget-text-editor\" data-id=\"6adc59c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tPour une extermination professionnelle de cafards \u00e0 Montr\u00e9al, vous pouvez compter sur Fenix Pest Solutions. Nous combinons technologie avanc\u00e9e et m\u00e9thodes \u00e9prouv\u00e9es pour traiter efficacement les infestations et offrir des r\u00e9sultats durables, tout en priorisant toujours votre s\u00e9curit\u00e9 et votre bien-\u00eatre. Nos services \u00e0 Montr\u00e9al et partout au Qu\u00e9bec figurent parmi les mieux not\u00e9s pour le contr\u00f4le parasitaire r\u00e9sidentiel et commercial. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-45fec84 e-con-full e-flex e-con e-child\" data-id=\"45fec84\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-bb91523 e-con-full e-flex e-con e-child\" data-id=\"bb91523\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b837c99 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"b837c99\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInDown&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eaad29b elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"eaad29b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-user\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M313.6 304c-28.7 0-42.5 16-89.6 16-47.1 0-60.8-16-89.6-16C60.2 304 0 364.2 0 438.4V464c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48v-25.6c0-74.2-60.2-134.4-134.4-134.4zM400 464H48v-25.6c0-47.6 38.8-86.4 86.4-86.4 14.6 0 38.3 16 89.6 16 51.7 0 74.9-16 89.6-16 47.6 0 86.4 38.8 86.4 86.4V464zM224 288c79.5 0 144-64.5 144-144S303.5 0 224 0 80 64.5 80 144s64.5 144 144 144zm0-240c52.9 0 96 43.1 96 96s-43.1 96-96 96-96-43.1-96-96 43.1-96 96-96z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u00c9quipe Exp\u00e9riment\u00e9e \t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tNotre \u00e9quipe de sp\u00e9cialistes poss\u00e8de des ann\u00e9es d\u2019exp\u00e9rience et d\u2019expertise, garantissant que votre maison ou votre entreprise reste exempte de nuisibles. Nous nous engageons \u00e0 fournir des solutions de contr\u00f4le des cafards efficaces, fiables et professionnelles. \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b21d74f e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"b21d74f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInDown&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1570ca1 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"1570ca1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-star\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M528.1 171.5L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6zM388.6 312.3l23.7 138.4L288 385.4l-124.3 65.3 23.7-138.4-100.6-98 139-20.2 62.2-126 62.2 126 139 20.2-100.6 98z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tService Cinq \u00c9toiles \t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAvec Fenix Pest Solutions, vous pouvez vous attendre \u00e0 un service rapide, courtois et professionnel \u00e0 chaque intervention. Notre engagement envers l\u2019excellence garantit une exp\u00e9rience fluide et sans tracas. \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0e3aa84 e-con-full e-flex e-con e-child\" data-id=\"0e3aa84\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3d153f7 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"3d153f7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInDown&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2d5b820 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"2d5b820\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tools\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M501.1 395.7L384 278.6c-23.1-23.1-57.6-27.6-85.4-13.9L192 158.1V96L64 0 0 64l96 128h62.1l106.6 106.6c-13.6 27.8-9.2 62.3 13.9 85.4l117.1 117.1c14.6 14.6 38.2 14.6 52.7 0l52.7-52.7c14.5-14.6 14.5-38.2 0-52.7zM331.7 225c28.3 0 54.9 11 74.9 31l19.4 19.4c15.8-6.9 30.8-16.5 43.8-29.5 37.1-37.1 49.7-89.3 37.9-136.7-2.2-9-13.5-12.1-20.1-5.5l-74.4 74.4-67.9-11.3L334 98.9l74.4-74.4c6.6-6.6 3.4-17.9-5.7-20.2-47.4-11.7-99.6.9-136.6 37.9-28.5 28.5-41.9 66.1-41.2 103.6l82.1 82.1c8.1-1.9 16.5-2.9 24.7-2.9zm-103.9 82l-56.7-56.7L18.7 402.8c-25 25-25 65.5 0 90.5s65.5 25 90.5 0l123.6-123.6c-7.6-19.9-9.9-41.6-5-62.7zM64 472c-13.2 0-24-10.8-24-24 0-13.3 10.7-24 24-24s24 10.7 24 24c0 13.2-10.7 24-24 24z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSolutions Optimales \t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tNotre syst\u00e8me de traitement exclusif Tri-Bloc offre jusqu\u2019\u00e0 trois fois plus de protection que les m\u00e9thodes traditionnelles, tout en restant s\u00e9curitaire pour votre famille, vos animaux et vos plantes. Cela assure un contr\u00f4le des cafards efficace et durable. \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fa560c1 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"fa560c1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInDown&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ef32c9c elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"ef32c9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"500\" viewBox=\"0 0 375 374.999991\" height=\"500\" preserveAspectRatio=\"xMidYMid meet\"><defs><clipPath id=\"f708c2d052\"><path d=\"M 170.90625 200.578125 L 203.90625 200.578125 L 203.90625 233.578125 L 170.90625 233.578125 Z M 170.90625 200.578125 \" clip-rule=\"nonzero\"><\/path><\/clipPath><clipPath id=\"15ef992382\"><path d=\"M 10 16.445312 L 367 16.445312 L 367 352.445312 L 10 352.445312 Z M 10 16.445312 \" clip-rule=\"nonzero\"><\/path><\/clipPath><\/defs><path fill=\"#ffffff\" d=\"M 196.382812 220.703125 L 196.546875 221.050781 C 196.632812 221.234375 196.773438 221.375 196.941406 221.464844 C 197.109375 221.558594 197.308594 221.597656 197.511719 221.566406 C 197.914062 221.5 198.21875 221.183594 198.277344 220.785156 L 198.324219 220.40625 C 197.917969 220.054688 197.503906 219.660156 197.152344 219.242188 C 196.941406 219.746094 196.667969 220.242188 196.382812 220.703125 Z M 196.382812 220.703125 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#ffffff\" d=\"M 194.6875 213.011719 C 194.875 212.984375 195.261719 213.421875 195.492188 214.226562 C 195.226562 214.523438 195.109375 214.941406 195.230469 215.351562 L 195.28125 215.535156 L 197.816406 215.144531 L 197.808594 214.953125 C 197.796875 214.523438 197.554688 214.160156 197.21875 213.964844 C 197.191406 213.125 197.429688 212.589844 197.617188 212.5625 C 197.804688 212.535156 197.933594 212.355469 197.90625 212.167969 C 197.878906 211.980469 197.699219 211.847656 197.511719 211.878906 C 196.972656 211.960938 196.519531 212.640625 196.519531 213.804688 C 196.492188 213.808594 196.460938 213.808594 196.4375 213.8125 L 196.195312 213.851562 C 196.164062 213.855469 196.140625 213.863281 196.113281 213.867188 C 195.761719 212.753906 195.125 212.246094 194.585938 212.332031 C 194.398438 212.359375 194.269531 212.539062 194.296875 212.726562 C 194.324219 212.910156 194.5 213.039062 194.6875 213.011719 Z M 194.6875 213.011719 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#ffffff\" d=\"M 198.398438 215.742188 C 198.28125 215.644531 198.128906 215.605469 197.980469 215.628906 L 196.871094 215.800781 L 197.285156 218.464844 C 197.300781 218.574219 197.34375 218.675781 197.410156 218.761719 C 198.023438 219.53125 198.878906 220.234375 199.460938 220.671875 C 199.71875 220.863281 200.085938 220.664062 200.058594 220.34375 C 199.984375 219.414062 199.785156 217.863281 199.226562 216.851562 C 198.9375 216.3125 198.664062 215.960938 198.398438 215.742188 Z M 198.398438 215.742188 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#ffffff\" d=\"M 196.789062 218.542969 L 196.375 215.878906 L 195.269531 216.046875 C 195.117188 216.074219 194.984375 216.152344 194.902344 216.28125 C 194.714844 216.574219 194.558594 216.996094 194.441406 217.59375 C 194.214844 218.722656 194.492188 220.265625 194.707031 221.171875 C 194.777344 221.488281 195.1875 221.566406 195.375 221.304688 C 195.800781 220.714844 196.402344 219.785156 196.757812 218.867188 C 196.796875 218.761719 196.804688 218.652344 196.789062 218.542969 Z M 196.789062 218.542969 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#ffffff\" d=\"M 189.152344 222.820312 L 188.601562 223.355469 L 187.699219 222.707031 C 187.5625 222.609375 187.371094 222.636719 187.269531 222.769531 L 186.257812 224.09375 C 186.199219 224.011719 186.132812 223.9375 186.058594 223.863281 C 185.992188 223.796875 185.914062 223.742188 185.832031 223.695312 L 186.191406 222.574219 C 186.226562 222.460938 186.199219 222.34375 186.113281 222.261719 L 185.21875 221.367188 L 185.511719 220.714844 C 185.582031 220.5625 185.511719 220.375 185.355469 220.308594 C 185.199219 220.238281 185.019531 220.308594 184.949219 220.460938 L 184.570312 221.304688 C 184.519531 221.421875 184.542969 221.5625 184.632812 221.652344 L 185.550781 222.566406 L 185.246094 223.515625 C 185.136719 223.5 185.03125 223.492188 184.929688 223.492188 C 185.070312 223.242188 185.085938 222.996094 184.847656 222.757812 C 184.660156 222.574219 184.328125 222.457031 184 222.425781 L 183.386719 221.265625 L 183.636719 220.96875 C 183.734375 220.855469 183.71875 220.691406 183.605469 220.597656 C 183.496094 220.503906 183.332031 220.515625 183.238281 220.628906 L 182.875 221.0625 C 182.804688 221.140625 182.792969 221.257812 182.839844 221.351562 L 183.421875 222.453125 C 183.316406 222.480469 183.230469 222.523438 183.171875 222.578125 C 183.117188 222.632812 183.074219 222.722656 183.046875 222.824219 L 181.949219 222.246094 C 181.851562 222.195312 181.738281 222.207031 181.65625 222.277344 L 181.222656 222.640625 C 181.113281 222.730469 181.097656 222.898438 181.191406 223.011719 C 181.289062 223.121094 181.453125 223.136719 181.5625 223.042969 L 181.859375 222.789062 L 183.019531 223.402344 C 183.054688 223.730469 183.171875 224.066406 183.355469 224.25 C 183.59375 224.488281 183.835938 224.476562 184.089844 224.335938 C 184.089844 224.4375 184.097656 224.542969 184.109375 224.648438 L 183.160156 224.953125 L 182.246094 224.039062 C 182.152344 223.945312 182.015625 223.921875 181.898438 223.976562 L 181.054688 224.351562 C 180.894531 224.421875 180.828125 224.605469 180.898438 224.761719 C 180.96875 224.914062 181.152344 224.984375 181.308594 224.914062 L 181.957031 224.621094 L 182.855469 225.519531 C 182.9375 225.597656 183.058594 225.632812 183.167969 225.597656 L 184.289062 225.234375 C 184.332031 225.316406 184.390625 225.394531 184.457031 225.464844 C 184.527344 225.535156 184.605469 225.601562 184.6875 225.664062 L 183.363281 226.675781 C 183.230469 226.777344 183.203125 226.964844 183.300781 227.101562 L 183.949219 228.007812 L 183.410156 228.554688 C 183.292969 228.675781 183.292969 228.871094 183.414062 228.992188 C 183.535156 229.109375 183.730469 229.109375 183.847656 228.988281 C 183.847656 228.988281 183.847656 228.988281 183.851562 228.984375 L 184.570312 228.25 C 184.675781 228.144531 184.691406 227.980469 184.601562 227.855469 L 183.976562 226.988281 L 185.308594 225.964844 C 185.425781 225.996094 185.542969 226.015625 185.65625 226.015625 C 185.5 226.3125 185.484375 226.625 185.734375 226.972656 L 185.378906 228.023438 C 185.339844 228.136719 185.367188 228.257812 185.453125 228.34375 L 186.308594 229.199219 L 185.984375 229.917969 C 185.914062 230.074219 185.984375 230.257812 186.144531 230.324219 C 186.261719 230.378906 186.398438 230.351562 186.484375 230.261719 C 186.511719 230.238281 186.535156 230.207031 186.546875 230.167969 L 186.953125 229.253906 C 187.007812 229.136719 186.980469 229.003906 186.890625 228.910156 L 186.019531 228.042969 L 186.21875 227.449219 C 186.929688 227.976562 188.003906 228.308594 188.453125 227.859375 C 188.898438 227.414062 188.5625 226.335938 188.042969 225.628906 L 188.632812 225.429688 L 189.503906 226.296875 C 189.59375 226.390625 189.730469 226.414062 189.847656 226.359375 L 190.761719 225.957031 C 190.796875 225.9375 190.828125 225.917969 190.855469 225.894531 C 190.941406 225.804688 190.972656 225.667969 190.917969 225.550781 C 190.847656 225.394531 190.667969 225.324219 190.511719 225.394531 L 189.789062 225.714844 L 188.941406 224.859375 C 188.859375 224.773438 188.734375 224.746094 188.625 224.785156 L 187.570312 225.140625 C 187.226562 224.894531 186.910156 224.910156 186.613281 225.070312 C 186.613281 224.953125 186.597656 224.839844 186.566406 224.71875 L 187.585938 223.386719 L 188.457031 224.011719 C 188.578125 224.101562 188.746094 224.085938 188.851562 223.980469 L 189.585938 223.261719 C 189.585938 223.261719 189.585938 223.261719 189.585938 223.257812 C 189.707031 223.140625 189.710938 222.945312 189.589844 222.824219 C 189.46875 222.703125 189.273438 222.699219 189.152344 222.820312 Z M 189.152344 222.820312 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#ffffff\" d=\"M 187.550781 209.988281 L 187.175781 210.101562 L 186.328125 209.496094 C 186.246094 209.433594 186.148438 209.421875 186.054688 209.457031 L 185.042969 209.832031 C 184.890625 209.886719 184.8125 210.058594 184.867188 210.207031 C 184.925781 210.359375 185.089844 210.4375 185.246094 210.386719 L 186.113281 210.066406 L 186.949219 210.667969 C 187.027344 210.722656 187.117188 210.738281 187.207031 210.714844 L 187.898438 210.503906 C 188.074219 210.734375 188.265625 210.960938 188.484375 211.1875 L 187.882812 211.785156 C 187.796875 211.875 187.769531 212.007812 187.828125 212.117188 L 188.246094 213.023438 L 187.933594 213.613281 C 187.855469 213.757812 187.90625 213.9375 188.054688 214.015625 C 188.167969 214.078125 188.3125 214.054688 188.402344 213.964844 C 188.425781 213.941406 188.4375 213.917969 188.453125 213.894531 L 188.835938 213.171875 C 188.882812 213.09375 188.882812 212.996094 188.84375 212.910156 L 188.449219 212.058594 L 188.917969 211.589844 C 189.257812 211.886719 189.613281 212.136719 189.957031 212.328125 L 189.761719 213.332031 C 189.746094 213.414062 189.765625 213.5 189.816406 213.566406 L 190.1875 214.046875 L 189.933594 214.691406 C 189.875 214.847656 189.949219 215.019531 190.101562 215.078125 C 190.210938 215.121094 190.339844 215.089844 190.417969 215.011719 C 190.445312 214.984375 190.46875 214.949219 190.484375 214.910156 L 190.800781 214.105469 C 190.839844 214.007812 190.824219 213.898438 190.761719 213.816406 L 190.371094 213.308594 L 190.511719 212.589844 C 191.171875 212.847656 191.773438 212.894531 192.1875 212.675781 L 188.136719 208.613281 C 187.898438 208.835938 187.542969 209.109375 187.164062 209.203125 C 187.261719 209.460938 187.390625 209.722656 187.550781 209.988281 Z M 187.550781 209.988281 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#ffffff\" d=\"M 193.546875 207.992188 L 192.957031 208.308594 L 192.050781 207.886719 C 191.9375 207.832031 191.800781 207.859375 191.71875 207.945312 L 191.121094 208.542969 C 190.902344 208.328125 190.675781 208.132812 190.441406 207.960938 L 190.648438 207.269531 C 190.675781 207.183594 190.660156 207.085938 190.605469 207.011719 L 190.003906 206.171875 L 190.320312 205.304688 C 190.378906 205.152344 190.296875 204.980469 190.148438 204.925781 C 189.992188 204.871094 189.820312 204.949219 189.765625 205.101562 L 189.390625 206.113281 C 189.355469 206.203125 189.375 206.308594 189.429688 206.386719 L 190.039062 207.234375 L 189.921875 207.609375 C 189.65625 207.449219 189.394531 207.316406 189.140625 207.21875 C 189.046875 207.601562 188.769531 207.953125 188.550781 208.195312 L 192.605469 212.246094 C 192.824219 211.832031 192.78125 211.226562 192.523438 210.570312 L 193.242188 210.429688 L 193.75 210.824219 C 193.832031 210.886719 193.941406 210.902344 194.039062 210.859375 L 194.839844 210.546875 C 194.878906 210.527344 194.914062 210.507812 194.941406 210.480469 C 195.023438 210.398438 195.054688 210.273438 195.007812 210.160156 C 194.949219 210.007812 194.777344 209.933594 194.625 209.996094 L 193.980469 210.25 L 193.5 209.878906 C 193.433594 209.828125 193.347656 209.804688 193.261719 209.824219 L 192.261719 210.019531 C 192.066406 209.671875 191.820312 209.320312 191.523438 208.976562 L 191.992188 208.507812 L 192.84375 208.90625 C 192.925781 208.941406 193.023438 208.941406 193.105469 208.898438 L 193.824219 208.511719 C 193.851562 208.5 193.875 208.484375 193.894531 208.464844 C 193.984375 208.375 194.011719 208.234375 193.949219 208.113281 C 193.871094 207.96875 193.6875 207.914062 193.546875 207.992188 Z M 193.546875 207.992188 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#ffffff\" d=\"M 188.441406 206.667969 C 188.257812 206.484375 187.867188 206.421875 187.488281 206.453125 C 187.253906 205.820312 187.203125 205.160156 187.335938 204.539062 C 187.367188 204.394531 187.273438 204.25 187.128906 204.21875 C 186.984375 204.1875 186.839844 204.277344 186.808594 204.425781 C 186.664062 205.105469 186.707031 205.820312 186.9375 206.507812 C 186.808594 206.488281 186.667969 206.527344 186.566406 206.625 C 186.464844 206.726562 186.425781 206.863281 186.445312 206.996094 C 185.757812 206.769531 185.046875 206.722656 184.363281 206.871094 C 184.222656 206.902344 184.128906 207.046875 184.160156 207.1875 C 184.191406 207.332031 184.332031 207.425781 184.476562 207.394531 C 185.101562 207.257812 185.757812 207.316406 186.390625 207.550781 C 186.355469 207.925781 186.421875 208.316406 186.609375 208.503906 C 186.953125 208.847656 187.425781 208.503906 187.933594 207.996094 C 188.4375 207.484375 188.785156 207.015625 188.441406 206.667969 Z M 188.441406 206.667969 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#ffffff\" d=\"M 183.484375 217.597656 C 182.996094 217.292969 182.515625 216.875 182.058594 216.476562 C 181.988281 216.410156 181.917969 216.351562 181.847656 216.289062 C 181.851562 216.285156 181.855469 216.277344 181.859375 216.277344 C 182.234375 215.789062 182.207031 215.140625 181.800781 214.828125 C 181.394531 214.519531 180.757812 214.65625 180.386719 215.148438 C 180.375 215.160156 180.367188 215.171875 180.363281 215.1875 C 179.859375 214.902344 179.3125 214.71875 178.703125 214.71875 C 176.394531 214.71875 175.503906 216.671875 175.421875 218.597656 L 175.363281 218.597656 C 174.835938 218.597656 174.40625 219.027344 174.40625 219.554688 C 174.40625 220.082031 174.835938 220.511719 175.363281 220.511719 L 178.375 220.511719 C 178.570312 220.511719 178.726562 220.671875 178.726562 220.878906 C 178.726562 221.074219 178.570312 221.234375 178.375 221.234375 L 177.136719 221.234375 C 176.96875 221.234375 176.832031 221.367188 176.832031 221.535156 C 176.832031 221.703125 176.96875 221.839844 177.136719 221.839844 L 178.375 221.839844 C 178.902344 221.839844 179.332031 221.410156 179.332031 220.871094 C 179.332031 220.34375 178.902344 219.914062 178.375 219.914062 L 175.363281 219.914062 C 175.167969 219.914062 175.007812 219.753906 175.007812 219.558594 C 175.007812 219.363281 175.167969 219.207031 175.363281 219.207031 L 178.597656 219.207031 C 178.5625 218.082031 177.910156 217.945312 177.832031 217.933594 C 177.667969 217.910156 177.550781 217.761719 177.578125 217.597656 C 177.597656 217.433594 177.75 217.316406 177.910156 217.335938 C 178.347656 217.390625 179.167969 217.851562 179.207031 219.210938 L 182.78125 219.210938 C 183.355469 219.210938 183.816406 218.9375 183.933594 218.527344 C 184.03125 218.171875 183.863281 217.832031 183.484375 217.597656 Z M 181.417969 217.773438 C 181.1875 217.773438 181.007812 217.59375 181.007812 217.367188 C 181.007812 217.136719 181.1875 216.957031 181.417969 216.957031 C 181.644531 216.957031 181.824219 217.136719 181.824219 217.367188 C 181.824219 217.59375 181.644531 217.773438 181.417969 217.773438 Z M 181.417969 217.773438 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><g clip-path=\"url(#f708c2d052)\"><path fill=\"#ffffff\" d=\"M 187.5 200.578125 C 178.347656 200.578125 170.90625 208.023438 170.90625 217.171875 C 170.90625 226.324219 178.347656 233.765625 187.5 233.765625 C 196.648438 233.765625 204.09375 226.324219 204.09375 217.171875 C 204.09375 208.023438 196.648438 200.578125 187.5 200.578125 Z M 172.976562 217.171875 C 172.976562 213.539062 174.324219 210.226562 176.539062 207.675781 L 197 228.136719 C 194.449219 230.347656 191.136719 231.699219 187.503906 231.699219 C 179.492188 231.695312 172.976562 225.179688 172.976562 217.171875 Z M 198.460938 226.671875 L 178 206.210938 C 180.550781 204 183.867188 202.648438 187.5 202.648438 C 195.503906 202.648438 202.019531 209.164062 202.019531 217.167969 C 202.019531 220.804688 200.671875 224.121094 198.460938 226.671875 Z M 198.460938 226.671875 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/g><path fill=\"#ffffff\" d=\"M 263.839844 104.101562 C 263.117188 93.863281 259.054688 83.875 251.683594 76.027344 L 246.617188 80.8125 C 253.878906 88.519531 257.441406 98.703125 257.050781 108.777344 L 263.839844 104.101562 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#ffffff\" d=\"M 98.152344 189.769531 C 99.960938 189.9375 101.769531 190.019531 103.578125 190.019531 C 109.335938 190.019531 114.957031 189.128906 120.1875 187.515625 C 118.101562 193.472656 116.792969 199.816406 116.375 206.382812 L 221.046875 133.789062 C 221.105469 132.925781 221.160156 132.09375 221.160156 131.203125 C 221.160156 119.070312 215.011719 108.359375 205.6875 102.015625 L 215.039062 90.441406 L 211.421875 87.519531 L 201.597656 99.675781 C 196.871094 97.3125 191.554688 95.949219 185.90625 95.949219 C 178.867188 95.949219 172.328125 98.035156 166.847656 101.597656 L 155.46875 87.519531 L 151.851562 90.441406 L 163.089844 104.378906 C 155.496094 110.835938 150.652344 120.460938 150.652344 131.203125 C 150.652344 135.929688 151.601562 140.4375 153.296875 144.527344 C 138.1875 146.671875 122.832031 139.660156 114.984375 126.414062 C 106.441406 111.976562 108.613281 93.222656 120.296875 80.8125 L 115.207031 76.027344 C 101.40625 90.691406 98.875 112.867188 108.972656 129.949219 C 117.15625 143.777344 132.289062 151.875 147.984375 151.875 C 148.121094 151.875 148.316406 151.875 148.484375 151.875 C 138.132812 158.46875 129.648438 167.707031 123.972656 178.667969 C 116.542969 182.089844 107.804688 183.675781 98.789062 182.816406 C 78.839844 180.949219 61.730469 167.734375 57.222656 150.734375 L 50.488281 152.515625 C 55.746094 172.296875 75.335938 187.628906 98.152344 189.769531 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#ffffff\" d=\"M 60.117188 226.304688 L 54.273438 230.085938 C 57.277344 234.734375 61.089844 238.628906 65.347656 241.773438 L 71.523438 237.515625 C 67.070312 234.621094 63.121094 230.921875 60.117188 226.304688 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#ffffff\" d=\"M 268.738281 189.769531 C 291.554688 187.628906 311.167969 172.296875 316.398438 152.515625 L 309.667969 150.734375 C 305.160156 167.734375 288.046875 180.949219 268.097656 182.816406 C 261.421875 183.453125 254.882812 182.730469 248.925781 180.921875 C 244.894531 172.351562 239.105469 164.757812 232.09375 158.523438 L 100.238281 250.007812 C 101.878906 249.703125 103.546875 249.398438 105.191406 248.894531 C 111.394531 247.003906 116.960938 243.804688 121.632812 239.628906 C 132.207031 268.175781 156.996094 292.746094 185.90625 292.746094 C 213.8125 292.746094 237.824219 269.820312 248.957031 242.578125 C 252.796875 245.304688 257.050781 247.476562 261.699219 248.894531 C 265.929688 250.175781 270.242188 250.816406 274.523438 250.816406 C 289.523438 250.816406 304.101562 243.21875 312.617188 230.085938 L 306.773438 226.304688 C 297.480469 240.578125 279.785156 247.113281 263.730469 242.21875 C 259.167969 240.855469 255.046875 238.601562 251.460938 235.734375 C 254.101562 227.445312 255.632812 218.929688 255.632812 210.609375 C 255.632812 203.015625 254.382812 195.753906 252.15625 188.878906 C 255.773438 189.601562 259.5 190.019531 263.3125 190.019531 C 265.121094 190.019531 266.929688 189.9375 268.738281 189.769531 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><g clip-path=\"url(#15ef992382)\"><path fill=\"#ffffff\" d=\"M 342.25 184.402344 C 342.25 271.960938 270.992188 343.191406 183.457031 343.191406 C 129.898438 343.191406 82.484375 316.507812 53.714844 275.800781 L 314.507812 94.863281 C 331.980469 120.378906 342.25 151.207031 342.25 184.402344 Z M 24.640625 184.402344 C 24.640625 96.839844 95.898438 25.582031 183.457031 25.582031 C 232.09375 25.582031 275.667969 47.589844 304.824219 82.148438 L 45.148438 262.277344 C 32.125 239.269531 24.640625 212.695312 24.640625 184.402344 Z M 366.84375 58.582031 L 357.746094 45.421875 L 312.558594 76.777344 C 281.703125 39.773438 235.265625 16.207031 183.457031 16.207031 C 90.695312 16.207031 15.265625 91.636719 15.265625 184.402344 C 15.265625 214.671875 23.332031 243.082031 37.410156 267.648438 L 10.699219 286.179688 L 19.828125 299.3125 L 46.007812 281.144531 C 76.476562 324.296875 126.699219 352.566406 183.457031 352.566406 C 276.195312 352.566406 351.625 277.136719 351.625 184.402344 C 351.625 149.203125 340.773438 116.539062 322.214844 89.523438 L 366.84375 58.582031 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tGarantie Sans Nuisibles \t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tNous garantissons notre travail. Si les cafards reviennent apr\u00e8s le traitement, nous revenons \u00e9galement. Notre garantie sans nuisibles refl\u00e8te notre engagement envers votre satisfaction et votre tranquillit\u00e9 d\u2019esprit. \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-576b4f7a e-flex e-con-boxed e-con e-parent\" data-id=\"576b4f7a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e8cff61 elementor-widget elementor-widget-heading\" data-id=\"7e8cff61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contactez-nous<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-396454c0 elementor-widget elementor-widget-text-editor\" data-id=\"396454c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pour toute demande d\u2019information ou d\u2019estimation, veuillez remplir le formulaire ci-dessous.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7e4b27d6 e-con-full e-flex e-con e-child\" data-id=\"7e4b27d6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2def7c8c e-con-full e-flex e-con e-child\" data-id=\"2def7c8c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3675afc8 elementor-widget elementor-widget-shortcode\" data-id=\"3675afc8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"wpforms-container \" id=\"wpforms-11\"><form id=\"wpforms-form-11\" class=\"wpforms-validate wpforms-form\" data-formid=\"11\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/4451\" data-token=\"80e4e34662a3eaf8fd12e0e6edc2d62a\" data-token-time=\"1778705525\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-11-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label\" for=\"wpforms-11-field_0\">Nom Complet <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-11-field_0\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][0][first]\" placeholder=\"Pr\u00e9nom\" required><label for=\"wpforms-11-field_0\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-11-field_0-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][0][last]\" placeholder=\"Nom\" required><label for=\"wpforms-11-field_0-last\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">Last<\/label><\/div><\/div><\/div><div id=\"wpforms-11-field_8-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"8\"><label class=\"wpforms-field-label\">Services<\/label><ul id=\"wpforms-11-field_8\"><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-11-field_8_2\" name=\"wpforms[fields][8][]\" value=\"\ud83e\udeb3Cafards\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-11-field_8_2\">\ud83e\udeb3Cafards<\/label><\/li><li class=\"choice-8 depth-1\"><input type=\"checkbox\" id=\"wpforms-11-field_8_8\" name=\"wpforms[fields][8][]\" value=\"\ud83d\udecf\ufe0fPunaises de lit\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-11-field_8_8\">\ud83d\udecf\ufe0fPunaises de lit<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"checkbox\" id=\"wpforms-11-field_8_7\" name=\"wpforms[fields][8][]\" value=\"\ud83d\udc00Rats \/ Souris\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-11-field_8_7\">\ud83d\udc00Rats \/ Souris<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-11-field_8_4\" name=\"wpforms[fields][8][]\" value=\"\ud83d\udc1cFourmis\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-11-field_8_4\">\ud83d\udc1cFourmis<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-11-field_8_5\" name=\"wpforms[fields][8][]\" value=\"\ud83d\udd77\ufe0fAraign\u00e9es\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-11-field_8_5\">\ud83d\udd77\ufe0fAraign\u00e9es<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-11-field_8_3\" name=\"wpforms[fields][8][]\" value=\"\ud83d\udc1dGu\u00eapes\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-11-field_8_3\">\ud83d\udc1dGu\u00eapes<\/label><\/li><li class=\"choice-9 depth-1\"><input type=\"checkbox\" id=\"wpforms-11-field_8_9\" name=\"wpforms[fields][8][]\" value=\"\ud83c\udf41Punaises de l\u2019\u00e9rable\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-11-field_8_9\">\ud83c\udf41Punaises de l\u2019\u00e9rable<\/label><\/li><li class=\"choice-10 depth-1\"><input type=\"checkbox\" id=\"wpforms-11-field_8_10\" name=\"wpforms[fields][8][]\" value=\"\ud83d\udc1ePuces\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-11-field_8_10\">\ud83d\udc1ePuces<\/label><\/li><\/ul><\/div><div id=\"wpforms-11-field_6-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-11-field_6\">Courriel<\/label><input type=\"email\" id=\"wpforms-11-field_6\" class=\"wpforms-field-large\" name=\"wpforms[fields][6]\" placeholder=\"abcd@hotmail.com\" spellcheck=\"false\" ><\/div><div id=\"wpforms-11-field_3-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-11-field_3\">Num\u00e9ro de t\u00e9l\u00e9phone <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"number\" id=\"wpforms-11-field_3\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][3]\" placeholder=\"514-123-4567\" step=\"any\" required><\/div><div id=\"wpforms-11-field_7-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"7\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-11-field_7\">Message<\/label><textarea id=\"wpforms-11-field_7\" class=\"wpforms-field-large\" name=\"wpforms[fields][7]\" placeholder=\"D\u00e9crivez bri\u00e8vement le probl\u00e8me (type de parasite, logement, urgence, etc.)\" ><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-field wpforms-field-hp\"><label for=\"wpforms-11-field-hp\" class=\"wpforms-field-label\">Message<\/label><input type=\"text\" name=\"wpforms[hp]\" id=\"wpforms-11-field-hp\" class=\"wpforms-field-medium\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"11\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/fenixpestsolutions.com\/en\/wp-json\/wp\/v2\/pages\/4451\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-11\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Obtenir un rappel\" aria-live=\"assertive\" value=\"wpforms-submit\">Obtenir un rappel<\/button><\/div><\/form><\/div>  <!-- .wpforms-container --><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6c4412e e-flex e-con-boxed e-con e-parent\" data-id=\"6c4412e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6c2f70f elementor-widget elementor-widget-html\" data-id=\"6c2f70f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script type=\"application\/ld+json\">\r\n{\r\n  \"@context\": \"https:\/\/schema.org\",\r\n  \"@type\": [\"LocalBusiness\", \"PestControl\"],\r\n  \"name\": \"Extermination de cafards \u00e0 Montr\u00e9al \u2013 Fenix Pest Solutions\",\r\n  \"description\": \"Traitement rapide et efficace contre les cafards \u00e0 Montr\u00e9al pour maisons et commerces.\",\r\n  \"keywords\": \"extermination cafards Montr\u00e9al, blattes, contr\u00f4le cafards\",\r\n  \"url\": \"https:\/\/fenixpestsolutions.com\/fr\/services\/cafards\/\",\r\n  \"logo\": \"https:\/\/fenixpestsolutions.com\/wp-content\/uploads\/2024\/08\/FENNIX-png-2048x987.webp\",\r\n  \"image\": \"https:\/\/fenixpestsolutions.com\/wp-content\/uploads\/2026\/01\/geotagged-gren-png.jpg\",\r\n  \"priceRange\": \"$$\",\r\n  \"telephone\": \"514-531-6074\",\r\n  \"email\": \"hello@fenixpestsolutions.com\",\r\n  \"address\": {\r\n    \"@type\": \"PostalAddress\",\r\n    \"addressLocality\": \"Montreal\",\r\n    \"addressRegion\": \"QC\",\r\n    \"addressCountry\": \"CA\"\r\n  },\r\n  \"openingHoursSpecification\": {\r\n    \"@type\": \"OpeningHoursSpecification\",\r\n    \"dayOfWeek\": [\r\n      \"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"\r\n    ],\r\n    \"opens\": \"09:00\",\r\n    \"closes\": \"21:00\"\r\n  }\r\n}\r\n<\/script>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-767a1c7 e-flex e-con-boxed e-con e-parent\" data-id=\"767a1c7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1afca04 elementor-widget elementor-widget-heading\" data-id=\"1afca04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FAQ <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-877002d elementor-widget elementor-widget-n-accordion\" data-id=\"877002d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1420\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-1420\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> En quoi consiste l\u2019extermination de cafards \u00e0 Montr\u00e9al ?  <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1420\" class=\"elementor-element elementor-element-1895457 e-con-full e-flex e-con e-child\" data-id=\"1895457\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d290e84 elementor-widget elementor-widget-text-editor\" data-id=\"d290e84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Fenix Pest Solutions offre une extermination professionnelle des cafards \u00e0 Montr\u00e9al qui cible l\u2019ensemble de la colonie. Nos sp\u00e9cialistes inspectent votre propri\u00e9t\u00e9, identifient les cachettes et appliquent des traitements s\u00e9curitaires et efficaces pour \u00e9liminer compl\u00e8tement les cafards.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1421\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1421\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Comment savoir si j\u2019ai un probl\u00e8me de cafards ?  <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1421\" class=\"elementor-element elementor-element-4bd12ec e-con-full e-flex e-con e-child\" data-id=\"4bd12ec\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6883e33 elementor-widget elementor-widget-text-editor\" data-id=\"6883e33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLes signes courants incluent la pr\u00e9sence de cafards la nuit, la d\u00e9couverte d\u2019excr\u00e9ments, une forte odeur de moisi ou la pr\u00e9sence d\u2019\u0153ufs ou de mues. Des observations r\u00e9currentes indiquent qu\u2019une extermination professionnelle de cafards \u00e0 Montr\u00e9al est n\u00e9cessaire. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1422\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1422\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Vos traitements sont-ils s\u00e9curitaires pour les enfants et les animaux ?  <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1422\" class=\"elementor-element elementor-element-5e4e533 e-con-full e-flex e-con e-child\" data-id=\"5e4e533\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5d58053 elementor-widget elementor-widget-text-editor\" data-id=\"5d58053\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tOui. Fenix Pest Solutions utilise des m\u00e9thodes respectueuses de l\u2019environnement pour l\u2019extermination des cafards \u00e0 Montr\u00e9al, garantissant que votre famille, vos animaux et vos plantes restent en s\u00e9curit\u00e9 tout en \u00e9liminant efficacement les nuisibles. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1423\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1423\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> \u00c0 quelle vitesse les cafards dispara\u00eetront-ils ?  <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1423\" class=\"elementor-element elementor-element-4d1f5ff e-con-full e-flex e-con e-child\" data-id=\"4d1f5ff\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5107ed2 elementor-widget elementor-widget-text-editor\" data-id=\"5107ed2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLes r\u00e9sultats varient, mais la plupart des propri\u00e9t\u00e9s constatent une r\u00e9duction notable de l\u2019activit\u00e9 des cafards en quelques jours. Notre suivi continu et nos mesures pr\u00e9ventives aident \u00e0 \u00e9viter leur retour. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1424\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1424\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Offrez-vous des services pr\u00e9ventifs apr\u00e8s le traitement ?  <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1424\" class=\"elementor-element elementor-element-1aecacc e-con-full e-flex e-con e-child\" data-id=\"1aecacc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6066974 elementor-widget elementor-widget-text-editor\" data-id=\"6066974\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tAbsolument. En plus de l\u2019extermination, Fenix Pest Solutions fournit des conseils sur la fermeture des points d\u2019entr\u00e9e, l\u2019am\u00e9lioration de l\u2019hygi\u00e8ne et d\u2019autres mesures pr\u00e9ventives pour r\u00e9duire le risque de futures infestations. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1425\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"6\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1425\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Combien de temps dure un traitement ?  <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1425\" class=\"elementor-element elementor-element-70ec204 e-con-full e-flex e-con e-child\" data-id=\"70ec204\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a600ce9 elementor-widget elementor-widget-text-editor\" data-id=\"a600ce9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLa plupart des traitements d\u2019extermination de cafards par Fenix Pest Solutions sont compl\u00e9t\u00e9s en quelques heures, selon la taille de votre propri\u00e9t\u00e9 et la gravit\u00e9 de l\u2019infestation. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1426\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"7\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1426\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Pouvez-vous g\u00e9rer de grandes infestations ?  <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1426\" class=\"elementor-element elementor-element-88e9022 e-con-full e-flex e-con e-child\" data-id=\"88e9022\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e0071fd elementor-widget elementor-widget-text-editor\" data-id=\"e0071fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tOui. Notre \u00e9quipe a l\u2019exp\u00e9rience n\u00e9cessaire pour traiter des infestations petites ou \u00e9tendues dans les maisons, appartements, bureaux et espaces commerciaux \u00e0 travers Montr\u00e9al et le Qu\u00e9bec. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1427\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"8\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1427\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Pourquoi choisir Fenix Pest Solutions ?  <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1427\" class=\"elementor-element elementor-element-8ba8271 e-con-full e-flex e-con e-child\" data-id=\"8ba8271\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50996d9 elementor-widget elementor-widget-text-editor\" data-id=\"50996d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tNous combinons expertise, m\u00e9thodes \u00e9cologiques, technologie avanc\u00e9e et garantie sans nuisibles. Avec Fenix Pest Solutions, vous b\u00e9n\u00e9ficiez d\u2019un contr\u00f4le des cafards fiable, efficace et durable \u00e0 Montr\u00e9al. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1428\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"9\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1428\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Un traitement de suivi est-il n\u00e9cessaire ?  <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1428\" class=\"elementor-element elementor-element-457fa1d e-con-full e-flex e-con e-child\" data-id=\"457fa1d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d1b335 elementor-widget elementor-widget-text-editor\" data-id=\"1d1b335\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDans certains cas, oui. Selon la gravit\u00e9 de l\u2019infestation, des visites de suivi peuvent \u00eatre recommand\u00e9es pour assurer une \u00e9limination compl\u00e8te et une pr\u00e9vention \u00e0 long terme. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1429\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"10\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1429\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Traitez-vous les propri\u00e9t\u00e9s commerciales ainsi que les r\u00e9sidences ?  <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1429\" class=\"elementor-element elementor-element-b886a25 e-con-full e-flex e-con e-child\" data-id=\"b886a25\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2f411cd elementor-widget elementor-widget-text-editor\" data-id=\"2f411cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tOui. Fenix Pest Solutions offre des services professionnels d\u2019extermination de cafards \u00e0 Montr\u00e9al pour les propri\u00e9t\u00e9s r\u00e9sidentielles et commerciales, incluant restaurants, bureaux et immeubles \u00e0 logements multiples. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Contr\u00f4le des cafards \u00e0 Montr\u00e9al et au Qu\u00e9bec Fenix Pest Solutions est un sp\u00e9cialiste reconnu des services de lutte contre les cafards \u00e0 Montr\u00e9al et au Qu\u00e9bec. Notre \u00e9quipe exp\u00e9riment\u00e9e utilise des m\u00e9thodes efficaces et \u00e9cologiques pour \u00e9liminer les cafards dans les maisons comme dans les entreprises. Nous r\u00e9alisons des inspections d\u00e9taill\u00e9es, \u00e9laborons des plans [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"parent":4487,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-4451","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/fenixpestsolutions.com\/en\/wp-json\/wp\/v2\/pages\/4451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fenixpestsolutions.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fenixpestsolutions.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fenixpestsolutions.com\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fenixpestsolutions.com\/en\/wp-json\/wp\/v2\/comments?post=4451"}],"version-history":[{"count":20,"href":"https:\/\/fenixpestsolutions.com\/en\/wp-json\/wp\/v2\/pages\/4451\/revisions"}],"predecessor-version":[{"id":6190,"href":"https:\/\/fenixpestsolutions.com\/en\/wp-json\/wp\/v2\/pages\/4451\/revisions\/6190"}],"up":[{"embeddable":true,"href":"https:\/\/fenixpestsolutions.com\/en\/wp-json\/wp\/v2\/pages\/4487"}],"wp:attachment":[{"href":"https:\/\/fenixpestsolutions.com\/en\/wp-json\/wp\/v2\/media?parent=4451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}